{"id":5479,"date":"2022-11-23T13:26:49","date_gmt":"2022-11-23T12:26:49","guid":{"rendered":"https:\/\/www.kaemmerinternational.de\/hannover\/?page_id=5479"},"modified":"2023-05-11T16:19:21","modified_gmt":"2023-05-11T14:19:21","slug":"application-form","status":"publish","type":"page","link":"https:\/\/www.kaemmerinternational.de\/hannover\/application-form\/","title":{"rendered":"Neue Anmeldung f\u00fcr KIBS: Krippe \/ Kita \/ Grundschule \/ Gymnasium"},"content":{"rendered":"\t<hr class=\"trenner\">\r\n\t\r\n    <form name=\"form1\" id=\"anmeldung2022\" enctype=\"multipart\/form-data\" method=\"post\" action=\"\/hannover\/wp-json\/wp\/v2\/pages\/5479\" >\r\n\t\t\r\n\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t<h3 id=\"at-28561\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-28561\" aria-expanded=\"false\">\u00dcberblick \u00fcber Verlauf des Anmeldeverfahrens<\/h3>\r\n\t\t\t<div id=\"ac-28561\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t<figure class=\"wp-block-image size-full\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1100\" height=\"2213\" src=\"https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/anleitung-de.png\" alt=\"\" class=\"wp-image-5856\" srcset=\"https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/anleitung-de.png 1100w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/anleitung-de-149x300.png 149w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/anleitung-de-509x1024.png 509w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/anleitung-de-763x1563.png 763w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/anleitung-de-768x1545.png 768w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/anleitung-de-1018x2048.png 1018w\" sizes=\"(max-width: 1100px) 100vw, 1100px\"><\/figure>\r\n\t\t\t\t1)\tBei Einschulung in die erste Klasse erfolgt anstelle der Probetage eine Abfrage beim Kindergarten des Kindes zum Stand der schulrelevanten Entwicklung, gefolgt von einem pers\u00f6nlichen Kennenlerntermin.\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\r\n\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t<h3 id=\"at-28562\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-28562\" aria-expanded=\"false\">1. Erziehungsberechtigte\/-r<\/h3>\r\n\t\t\t<div id=\"ac-28562\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\t<select name=\"e1anrede\" id=\"e1anrede\">\r\n\t\t\t\t\t<option>Herr<\/option>\r\n\t\t\t\t\t<option>Frau<\/option>\r\n\t\t\t\t<\/select>\r\n\t\t\t\t<label>Titel<\/label><input type=\"text\" name=\"e1titel\" id=\"e1titel\">\r\n\t\t\t\t<label>Vorname<\/label><input type=\"text\" name=\"e1vorname\" id=\"e1vorname\">\r\n\t\t\t\t<label>Nachname<\/label><input type=\"text\" name=\"e1nachname\" id=\"e1nachname\">\r\n\t\t\t\t<label>Adresse<\/label><input type=\"text\" name=\"e1strasse\" id=\"e1strasse\">\r\n\t\t\t\t<label>PLZ<\/label><input type=\"text\" name=\"e1plz\" id=\"e1plz\">\r\n\t\t\t\t<label>Ort<\/label><input type=\"text\" name=\"e1ort\" id=\"e1ort\">\r\n\t\t\t\t<label>Telefon<\/label><input type=\"text\" name=\"e1telefon\" id=\"e1telefon\">\r\n\t\t\t\t<label>Mobil<\/label><input type=\"text\" name=\"e1mobil\" id=\"e1mobil\">\r\n\t\t\t\t<label>Email<\/label><input type=\"text\" name=\"e1email\" id=\"e1email\">\r\n\t\t\t\t<label>Arbeitgeber<\/label><input type=\"text\" name=\"e1arbeitgeber\" id=\"e1arbeitgeber\">\r\n\t\t\t\t<label>Berufsfeld<\/label><input type=\"text\" name=\"e1berufsfeld\" id=\"e1berufsfeld\">\r\n\t\t\t\t<label>Aktuelle \/ letzte berufliche Position<\/label><input type=\"text\" name=\"e1position\" id=\"e1position\">\r\n\t\t\t\t<label>Muttersprache<\/label><input type=\"text\" name=\"e1muttersprache\" id=\"e1muttersprache\">\r\n\t\t\t\t<label>Zweitsprache<\/label><input type=\"text\" name=\"e1zweitesprache\" id=\"e1zweitesprache\">\r\n\t\t\t\t<label>Gew\u00fcnschte Sprache der Kommunikation<\/label>\r\n\t\t\t\t<select name=\"kommunikation\" id=\"kommunikation\">\r\n\t\t\t\t\t<option>Deutsch<\/option>\r\n\t\t\t\t\t<option>English<\/option>\r\n\t\t\t\t<\/select>\r\n\t\t\t\t<label>Seit wann leben die Kinder in Deutschland?<\/label><input type=\"text\" name=\"zeitindeutschland\" id=\"zeitindeutschland\">\r\n\t\t\t\t<label>Alleine sorgeberechtigt<\/label>\r\n\t\t\t\t<select name=\"sorgeberechtigung\" id=\"sorgeberechtigung\">\r\n\t\t\t\t\t<option>Nein<\/option>\r\n\t\t\t\t\t<option>Ja<\/option>\r\n\t\t\t\t<\/select>\r\n\t\t\t\t<hr class=\"trenner\">\r\n\t\t\t\tBei getrenntlebenden Eltern ben\u00f6tigen wir eine Bescheinigung \u00fcber das Sorgerecht!\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t<h3 id=\"at-28563\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-28563\" aria-expanded=\"false\">2. Erziehungsberechtigte\/-r<\/h3>\r\n\t\t\t<div id=\"ac-28563\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\t<select name=\"e2anrede\" id=\"e2anrede\">\r\n\t\t\t\t\t<option>Herr<\/option>\r\n\t\t\t\t\t<option>Frau<\/option>\r\n\t\t\t\t<\/select>\r\n\t\t\t\t<label>Titel<\/label><input type=\"text\" name=\"e2titel\" id=\"e2titel\">\r\n\t\t\t\t<label>Vorname<\/label><input type=\"text\" name=\"e2vorname\" id=\"e2vorname\">\r\n\t\t\t\t<label>Nachname<\/label><input type=\"text\" name=\"e2nachname\" id=\"e2nachname\">\r\n\t\t\t\t<label>Adresse<\/label><input type=\"text\" name=\"e2strasse\" id=\"e2strasse\">\r\n\t\t\t\t<label>PLZ<\/label><input type=\"text\" name=\"e2plz\" id=\"e2plz\">\r\n\t\t\t\t<label>Ort<\/label><input type=\"text\" name=\"e2ort\" id=\"e2ort\">\r\n\t\t\t\t<label>Telefon<\/label><input type=\"text\" name=\"e2telefon\" id=\"e2telefon\">\r\n\t\t\t\t<label>Mobil<\/label><input type=\"text\" name=\"e2mobil\" id=\"e2mobil\">\r\n\t\t\t\t<label>Email<\/label><input type=\"text\" name=\"e2email\" id=\"e2email\">\r\n\t\t\t\t<label>Arbeitgeber<\/label><input type=\"text\" name=\"e2arbeitgeber\" id=\"e2arbeitgeber\">\r\n\t\t\t\t<label>Berufsfeld<\/label><input type=\"text\" name=\"e2berufsfeld\" id=\"e2berufsfeld\">\r\n\t\t\t\t<label>Aktuelle \/ letzte berufliche Position<\/label><input type=\"text\" name=\"e2position\" id=\"e2position\">\r\n\t\t\t\t<label>Muttersprache<\/label><input type=\"text\" name=\"e2muttersprache\" id=\"e2muttersprache\">\r\n\t\t\t\t<label>Zweitsprache<\/label><input type=\"text\" name=\"e2zweitesprache\" id=\"e2zweitesprache\">\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t<h3 id=\"at-28564\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-28564\" aria-expanded=\"false\">1. Kind<\/h3>\r\n\t\t\t<div id=\"ac-28564\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\t<div class=\"radios\">\r\n\t\t\t\tAnmeldung f\u00fcr<br \/>\t\t\t\t\t<span><input type=\"radio\" id=\"k1ksa\" name=\"k1schulekita\" value=\"Krippe\"><label class=\"radiolabel\" for=\"k1ksa\">Krippe<\/label><\/span>\r\n\t\t\t\t\t<span><input type=\"radio\" id=\"k1ksb\" name=\"k1schulekita\" value=\"Kindergarten\"><label class=\"radiolabel\" for=\"k1ksb\">Kindergarten<\/label><\/span>\r\n\t\t\t\t\t<span><input type=\"radio\" id=\"k1ksc\" name=\"k1schulekita\" value=\"Grundschule\"><label class=\"radiolabel\" for=\"k1ksc\">Grundschule<\/label><\/span>\r\n\t\t\t\t\t<span class=\"k1ersteklasse\" style=\"display:none\"><input type=\"checkbox\" class=\"k1ersteklasse\" name=\"k1ersteklasse\" style=\"display:none\" value=\"1\"><label class=\"radiolabel\" for=\"k1ersteklasse\">Anmeldung f\u00fcr die erste Klasse?<\/label><\/span>\r\n\t\t\t\t\t<span><input type=\"radio\" id=\"k1ksd\" name=\"k1schulekita\" value=\"Gymnasium\"><label class=\"radiolabel\" for=\"k1ksd\">Gymnasium<\/label><\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"radios\">\r\n\t\t\t\tHaben Sie bereits Kinder in unserer Einrichtung?<br \/>\t\t\t\t\t<span><input type=\"radio\" id=\"k1geschwisternein\" name=\"k1geschwister\" value=\"Nein\"><label class=\"radiolabel\" for=\"k1geschwisternein\">Nein<\/label><\/span>\r\n\t\t\t\t\t<span><input type=\"radio\" id=\"k1geschwisterinkita\" name=\"k1geschwister\" value=\"Ja, in der Krippe \/ KiTa\"><label class=\"radiolabel\" for=\"k1geschwisterinkita\">Ja, in Krippe \/ Kindergarten<\/label><\/span>\r\n\t\t\t\t\t<span><input type=\"radio\" id=\"k1geschwisterings\" name=\"k1geschwister\" value=\"Ja, in der Grundschule\"><label class=\"radiolabel\" for=\"k1geschwisterings\">Ja, in der Grundschule<\/label><\/span>\r\n\t\t\t\t\t<span><input type=\"radio\" id=\"k1geschwisteringym\" name=\"k1geschwister\" value=\"Ja, im Gymnasium\"><label class=\"radiolabel\" for=\"k1geschwisteringym\">Ja, im Gymnasium<\/label><\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<hr class=\"trenner\">\r\n\t\t\t\t<label>Geschlecht:<\/label>\r\n\t\t\t\t\t<select name=\"k1geschlecht\" id=\"k1geschlecht\">\r\n\t\t\t\t\t\t<option>m<\/option>\r\n\t\t\t\t\t\t<option>w<\/option>\r\n\t\t\t\t\t\t<option>d<\/option>\r\n\t\t\t\t\t<\/select>\r\n\t\t\t\t<label>Vorname<\/label><input type=\"text\" name=\"k1vorname\" id=\"k1vorname\">\r\n\t\t\t\t<label>Nachname<\/label><input type=\"text\" name=\"k1nachname\" id=\"k1nachname\">\r\n\t\t\t\t<label>Geburtstag<\/label><input type=\"date\" name=\"k1geburtstag\" id=\"k1geburtstag\">\r\n\t\t\t\t<label>Geburtsort<\/label><input type=\"text\" name=\"k1geburtsort\" id=\"k1geburtsort\">\r\n\t\t\t\t<label>Nationalit\u00e4t<\/label><input type=\"text\" name=\"k1nationalitaet\" id=\"k1nationalitaet\">\r\n\t\t\t\t<label>Muttersprache<\/label><input type=\"text\" name=\"k1sprache1\" id=\"k1sprache1\">\r\n\t\t\t\t<label>Zweitsprache<\/label><input type=\"text\" name=\"k1sprache2\" id=\"k1sprache2\">\r\n\t\t\t\t<label>Religion<\/label><input type=\"text\" name=\"k1religion\" id=\"k1religion\">\r\n\t\t\t\t<label>Kind lebt bei<\/label><input type=\"text\" name=\"k1lebtbei\" id=\"k1lebtbei\">\r\n\t\t\t\t<label>Startjahr<\/label><input type=\"text\" name=\"k1startjahr\" id=\"k1startjahr\">\r\n\t\t\t\t<label>Aktuell in (KiTa \/ Klasse...)<\/label><input type=\"text\" name=\"k1aktuellin\" id=\"k1aktuellin\">\r\n\t\t\t\t<label>Interesse Nutzung KIBS-Schulbus?<\/label>\r\n\t\t\t\t<select name=\"k1bus\" id=\"k1bus\">\r\n\t\t\t\t\t<option>Ja<\/option>\r\n\t\t\t\t\t<option>Nein<\/option>\r\n\t\t\t\t<\/select>\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t\t\t\t<h3 id=\"at-18916\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-18916\" aria-expanded=\"false\">Bei Anmeldung f\u00fcr Schule<\/h3>\r\n\t\t\t\t\t<div id=\"ac-18916\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\t\t\tF\u00fcr Schulanf\u00e4nger in Klasse 1 bitte angeben:\t\t\t\t\t\t\r\n\t\t\t\t\t\t<br \/> \r\n\t\t\t\t\t\tGem\u00e4\u00df Wohnort zust\u00e4ndige \u00f6rtliche staatliche Grundschule:\t\t\t\t\t\t<label>Name<\/label>\r\n\t\t\t\t\t\t<input type=\"text\" name=\"k1klasse1schulname\" id=\"k1klasse1schulname\">\r\n\t\t\t\t\t\t<label>Ort<\/label>\r\n\t\t\t\t\t\t<input type=\"text\" name=\"k1klasse1schulort\" id=\"k1klasse1schulort\">\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\tDie \u00f6rtlichen staatlichen Grundschulen sind dazu verpflichtet, darauf zu achten, dass die Schulpflicht gem\u00e4\u00df Schulgesetz eingehalten wird. Diese bekommen die Namen der schulpflichtig werdenden Kinder vom B\u00fcrgeramt der St\u00e4dte\/Gemeinden gemeldet. Wenn Ihr Kind bei KIBS aufgenommen wird, sendet KIBS zu diesem Zweck eine Aufnahmebest\u00e4tigung an die \u00f6rtliche staatliche Grundschule.\t\t\t\t\t\t<p><\/p>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<h4>Erforderliche Informationen f\u00fcr beide Schulformen<\/h4>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t1. Bitte f\u00fcgen Sie diesem Anmeldeformular die letzten drei Zeugnisse Ihres Kindes bei.\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<!--<label class=\"custom-uploader\" for=\"file\">Zeugnisse hochladen<\/label>-->\r\n\t\t\t\t\t\t<input id=\"file\" multiple=\"multiple\" accept=\"image\/jpeg,image\/png,application\/pdf\" name=\"k1attachments[]\" type=\"file\" \/>\r\n\t\t\t\t\t\t<hr class=\"trenner\">\r\n\t\t\t\t\t\t2. Ist bei Ihrem Kind bereits F\u00f6rderbedarf festgestellt worden?\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"radios\">\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k1foerderbedarfnein\">Nein<\/label><input type=\"radio\" id=\"k1foerderbedarfnein\" name=\"k1foerderbedarf\" value=\"nein\"><\/span>\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k1foerderbedarfja\">Ja<\/label><input type=\"radio\" id=\"k1foerderbedarfja\" name=\"k1foerderbedarf\" value=\"ja\"><\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<hr class=\"trenner\">\r\n\t\t\t\t\t\t3. Gibt es gesundheitliche Herausforderungen, die Einfluss auf den Schulalltag haben oder Dauer-medikation erfordern (z.B. Seh-\/H\u00f6rsch\u00e4digung\/chronische Krankheiten \/Allergien o. \u00e4.?)\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"radios\">\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k1gesundheitnein\">\r\n\t\t\t\t\t\tNein<\/label><input type=\"radio\" id=\"k1gesundheitnein\" name=\"k1gesundheit\" value=\"nein\"><\/span>\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k1gesundheitja\">\r\n\t\t\t\t\t\tJa<\/label><input type=\"radio\" id=\"k1gesundheitja\" name=\"k1gesundheit\" value=\"ja\"><\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<textarea id=\"k1gesundheitdetails\" name=\"k1gesundheitdetails\" rows=\"4\" cols=\"50\">Falls ja, bitte hier angeben:<\/textarea>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t<h3 id=\"at-28565\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-28565\" aria-expanded=\"false\">2. Kind<\/h3>\r\n\t\t\t<div id=\"ac-28565\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\t<div class=\"radios\">\r\n\t\t\t\tAnmeldung f\u00fcr<br \/>\t\t\t\t\t<span><input type=\"radio\" id=\"k2ksa\" name=\"k2schulekita\" value=\"Krippe\"><label class=\"radiolabel\" for=\"k2ksa\">Krippe<\/label><\/span>\r\n\t\t\t\t\t<span><input type=\"radio\" id=\"k2ksb\" name=\"k2schulekita\" value=\"Kindergarten\"><label class=\"radiolabel\" for=\"k2ksb\">Kindergarten<\/label><\/span>\r\n\t\t\t\t\t<span><input type=\"radio\" id=\"k2ksc\" name=\"k2schulekita\" value=\"Grundschule\"><label class=\"radiolabel\" for=\"k1ksc\">Grundschule<\/label><\/span>\r\n\t\t\t\t\t<span class=\"k2ersteklasse\" style=\"display:none\"><input type=\"checkbox\" class=\"k2ersteklasse\" name=\"k2ersteklasse\" style=\"display:none\" value=\"1\"><label class=\"radiolabel\" for=\"k2ersteklasse\">Anmeldung f\u00fcr die erste Klasse?<\/label><\/span>\r\n\t\t\t\t\t<span><input type=\"radio\" id=\"k2ksd\" name=\"k2schulekita\" value=\"Gymnasium\"><label class=\"radiolabel\" for=\"k1ksd\">Gymnasium<\/label><\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<hr class=\"trenner\">\r\n\t\t\t\t<label>Geschlecht:<\/label>\r\n\t\t\t\t\t<select name=\"k2geschlecht\" id=\"k2geschlecht\">\r\n\t\t\t\t\t\t<option>m<\/option>\r\n\t\t\t\t\t\t<option>w<\/option>\r\n\t\t\t\t\t\t<option>d<\/option>\r\n\t\t\t\t\t<\/select>\r\n\t\t\t\t<label>Vorname<\/label><input type=\"text\" name=\"k2vorname\" id=\"k2vorname\">\r\n\t\t\t\t<label>Nachname<\/label><input type=\"text\" name=\"k2nachname\" id=\"k2nachname\">\r\n\t\t\t\t<label>Geburtstag<\/label><input type=\"date\" name=\"k2geburtstag\" id=\"k2geburtstag\">\r\n\t\t\t\t<label>Geburtsort<\/label><input type=\"text\" name=\"k2geburtsort\" id=\"k2geburtsort\">\r\n\t\t\t\t<label>Nationalit\u00e4t<\/label><input type=\"text\" name=\"k2nationalitaet\" id=\"k2nationalitaet\">\r\n\t\t\t\t<label>Muttersprache<\/label><input type=\"text\" name=\"k2sprache1\" id=\"k2sprache1\">\r\n\t\t\t\t<label>Zweitsprache<\/label><input type=\"text\" name=\"k2sprache2\" id=\"k2sprache2\">\r\n\t\t\t\t<label>Religion<\/label><input type=\"text\" name=\"k2religion\" id=\"k2religion\">\r\n\t\t\t\t<label>Kind lebt bei<\/label><input type=\"text\" name=\"k2lebtbei\" id=\"k2lebtbei\">\r\n\t\t\t\t<label>Startjahr<\/label><input type=\"text\" name=\"k2startjahr\" id=\"k2startjahr\">\r\n\t\t\t\t<label>Aktuell in (KiTa \/ Klasse...)<\/label><input type=\"text\" name=\"k2aktuellin\" id=\"k2aktuellin\">\r\n\t\t\t\t<label>Interesse Nutzung KIBS-Schulbus?<\/label>\r\n\t\t\t\t<select name=\"k2bus\" id=\"k2bus\">\r\n\t\t\t\t\t<option>Ja<\/option>\r\n\t\t\t\t\t<option>Nein<\/option>\r\n\t\t\t\t<\/select>\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t\t\t\t<h3 id=\"at-22566\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-22566\" aria-expanded=\"false\">Bei Anmeldung f\u00fcr Schule<\/h3>\r\n\t\t\t\t\t<div id=\"ac-22566\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\t\t\t<!--\r\n\t\t\t\t\t\t<input id=\"file\" accept=\"image\/jpeg,image\/gif,image\/png,application\/pdf,image\/x-eps\" name=\"k2attachment1\" type=\"file\" \/>\r\n\t\t\t\t\t\t<input id=\"file\" accept=\"image\/jpeg,image\/gif,image\/png,application\/pdf,image\/x-eps\" name=\"k2attachment2\" type=\"file\" \/>\r\n\t\t\t\t\t\t<input id=\"file\" accept=\"image\/jpeg,image\/gif,image\/png,application\/pdf,image\/x-eps\" name=\"k2attachment3\" type=\"file\" \/>\r\n\t\t\t\t\t\t--->\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\tF\u00fcr Schulanf\u00e4nger in Klasse 1 bitte angeben:\t\t\t\t\t\t\r\n\t\t\t\t\t\t<br \/> \r\n\t\t\t\t\t\tGem\u00e4\u00df Wohnort zust\u00e4ndige \u00f6rtliche staatliche Grundschule:\t\t\t\t\t\t<label>Name<\/label>\r\n\t\t\t\t\t\t<input type=\"text\" name=\"k2klasse1schulname\" id=\"k2klasse1schulname\">\r\n\t\t\t\t\t\t<label>Ort<\/label>\r\n\t\t\t\t\t\t<input type=\"text\" name=\"k2klasse1schulort\" id=\"k2klasse1schulort\">\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\tDie \u00f6rtlichen staatlichen Grundschulen sind dazu verpflichtet, darauf zu achten, dass die Schulpflicht gem\u00e4\u00df Schulgesetz eingehalten wird. Diese bekommen die Namen der schulpflichtig werdenden Kinder vom B\u00fcrgeramt der St\u00e4dte\/Gemeinden gemeldet. Wenn Ihr Kind bei KIBS aufgenommen wird, sendet KIBS zu diesem Zweck eine Aufnahmebest\u00e4tigung an die \u00f6rtliche staatliche Grundschule.\t\t\t\t\t\t<p><\/p>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<h4>Erforderliche Informationen f\u00fcr beide Schulformen<\/h4>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t1. Bitte f\u00fcgen Sie diesem Anmeldeformular die letzten drei Zeugnisse Ihres Kindes bei.\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<!--<label class=\"custom-uploader\" for=\"file\">Zeugnisse hochladen<\/label>-->\r\n\t\t\t\t\t\t<input id=\"file\" multiple=\"multiple\" accept=\"image\/jpeg,image\/png,application\/pdf\" name=\"k2attachments\" type=\"file\" \/>\r\n\t\t\t\t\t\t<hr class=\"trenner\">\r\n\t\t\t\t\t\t2. Ist bei Ihrem Kind bereits F\u00f6rderbedarf festgestellt worden?\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"radios\">\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k2foerderbedarfnein\">Nein<\/label><input type=\"radio\" id=\"k2foerderbedarfnein\" name=\"k2foerderbedarf\" value=\"nein\"><\/span>\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k2foerderbedarfja\">Ja<\/label><input type=\"radio\" id=\"k2foerderbedarfja\" name=\"k2foerderbedarf\" value=\"ja\"><\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<hr class=\"trenner\">\r\n\t\t\t\t\t\t3. Gibt es gesundheitliche Herausforderungen, die Einfluss auf den Schulalltag haben oder Dauer-medikation erfordern (z.B. Seh-\/H\u00f6rsch\u00e4digung\/chronische Krankheiten \/Allergien o. \u00e4.?)\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"radios\">\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k2gesundheitnein\">\r\n\t\t\t\t\t\tNein<\/label><input type=\"radio\" id=\"k2gesundheitnein\" name=\"k2gesundheit\" value=\"nein\"><\/span>\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k2gesundheitja\">\r\n\t\t\t\t\t\tJa<\/label><input type=\"radio\" id=\"k2gesundheitja\" name=\"k2gesundheit\" value=\"ja\"><\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<textarea id=\"k2gesundheitdetails\" name=\"k2gesundheitdetails\" rows=\"4\" cols=\"50\">Falls ja, bitte hier angeben:<\/textarea>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t<h3 id=\"at-28566\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-28566\" aria-expanded=\"false\">3. Kind<\/h3>\r\n\t\t\t<div id=\"ac-28566\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\t<div class=\"radios\">\r\n\t\t\t\tAnmeldung f\u00fcr<br \/>\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k3ksa\">Krippe<\/label><input type=\"radio\" id=\"k3ksa\" name=\"k3schulekita\" value=\"Krippe\"><\/span>\r\n\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k3ksb\">Kindergarten<\/label><input type=\"radio\" id=\"k3ksb\" name=\"k3schulekita\" value=\"Kindergarten\"><\/span>\r\n\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k1ksc\">Grundschule<\/label><input type=\"radio\" id=\"k3ksc\" name=\"k3schulekita\" value=\"Grundschule\"><\/span>\r\n\t\t\t\t\t<span class=\"k3ersteklasse\" style=\"display:none\"><input type=\"checkbox\" class=\"k3ersteklasse\" name=\"k3ersteklasse\" style=\"display:none\" value=\"1\"><label class=\"radiolabel\" for=\"k3ersteklasse\">Anmeldung f\u00fcr die erste Klasse?<\/label><\/span>\r\n\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k1ksd\">Gymnasium<\/label><input type=\"radio\" id=\"k3ksd\" name=\"k3schulekita\" value=\"Gymnasium\"><\/span>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t<hr class=\"trenner\">\r\n\t\t\t\t<label>Geschlecht:<\/label>\r\n\t\t\t\t\t<select name=\"k3geschlecht\" id=\"k3geschlecht\">\r\n\t\t\t\t\t\t<option>m<\/option>\r\n\t\t\t\t\t\t<option>w<\/option>\r\n\t\t\t\t\t\t<option>d<\/option>\r\n\t\t\t\t\t<\/select>\r\n\t\t\t\t<label>Vorname<\/label><input type=\"text\" name=\"k3vorname\" id=\"k3vorname\">\r\n\t\t\t\t<label>Nachname<\/label><input type=\"text\" name=\"k3nachname\" id=\"k3nachname\">\r\n\t\t\t\t<label>Geburtstag<\/label><input type=\"date\" name=\"k3geburtstag\" id=\"k3geburtstag\">\r\n\t\t\t\t<label>Geburtsort<\/label><input type=\"text\" name=\"k3geburtsort\" id=\"k3geburtsort\">\r\n\t\t\t\t<label>Nationalit\u00e4t<\/label><input type=\"text\" name=\"k3nationalitaet\" id=\"k3nationalitaet\">\r\n\t\t\t\t<label>Muttersprache<\/label><input type=\"text\" name=\"k3sprache1\" id=\"k3sprache1\">\r\n\t\t\t\t<label>Zweitsprache<\/label><input type=\"text\" name=\"k3sprache2\" id=\"k3sprache2\">\r\n\t\t\t\t<label>Religion<\/label><input type=\"text\" name=\"k3religion\" id=\"k3religion\">\r\n\t\t\t\t<label>Kind lebt bei<\/label><input type=\"text\" name=\"k3lebtbei\" id=\"k3lebtbei\">\r\n\t\t\t\t<label>Startjahr<\/label><input type=\"text\" name=\"k3startjahr\" id=\"k3startjahr\">\r\n\t\t\t\t<label>Aktuell in (KiTa \/ Klasse...)<\/label><input type=\"text\" name=\"k3aktuellin\" id=\"k3aktuellin\">\r\n\t\t\t\t<label>Interesse Nutzung KIBS-Schulbus?<\/label>\r\n\t\t\t\t<select name=\"k3bus\" id=\"k3bus\">\r\n\t\t\t\t\t<option>Ja<\/option>\r\n\t\t\t\t\t<option>Nein<\/option>\r\n\t\t\t\t<\/select>\r\n\t\t\t\t\r\n\t\t\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t\t\t\t<h3 id=\"at-77766\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-77766\" aria-expanded=\"false\">Bei Anmeldung f\u00fcr Schule<\/h3>\r\n\t\t\t\t\t<div id=\"ac-77766\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\t\t\tF\u00fcr Schulanf\u00e4nger in Klasse 1 bitte angeben:\t\t\t\t\t\t\r\n\t\t\t\t\t\t<br \/> \r\n\t\t\t\t\t\tGem\u00e4\u00df Wohnort zust\u00e4ndige \u00f6rtliche staatliche Grundschule:\t\t\t\t\t\t<label>Name<\/label>\r\n\t\t\t\t\t\t<input type=\"text\" name=\"k3klasse1schulname\" id=\"k3klasse1schulname\">\r\n\t\t\t\t\t\t<label>Ort<\/label>\r\n\t\t\t\t\t\t<input type=\"text\" name=\"k3klasse1schulort\" id=\"k3klasse1schulort\">\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\tDie \u00f6rtlichen staatlichen Grundschulen sind dazu verpflichtet, darauf zu achten, dass die Schulpflicht gem\u00e4\u00df Schulgesetz eingehalten wird. Diese bekommen die Namen der schulpflichtig werdenden Kinder vom B\u00fcrgeramt der St\u00e4dte\/Gemeinden gemeldet. Wenn Ihr Kind bei KIBS aufgenommen wird, sendet KIBS zu diesem Zweck eine Aufnahmebest\u00e4tigung an die \u00f6rtliche staatliche Grundschule.\t\t\t\t\t\t<p><\/p>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<h4>Erforderliche Informationen f\u00fcr beide Schulformen<\/h4>\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t1. Bitte f\u00fcgen Sie diesem Anmeldeformular die letzten drei Zeugnisse Ihres Kindes bei.\t\t\t\t\t\t\r\n\t\t\t\t\t\t\r\n\t\t\t\t\t\t<!--<label class=\"custom-uploader\" for=\"file\">Zeugnisse hochladen<\/label>-->\r\n\t\t\t\t\t\t<input id=\"file\" multiple=\"multiple\" accept=\"image\/jpeg,image\/png,application\/pdf\" name=\"k3attachments\" type=\"file\" \/>\r\n\t\t\t\t\t\t<hr class=\"trenner\">\r\n\t\t\t\t\t\t2. Ist bei Ihrem Kind bereits F\u00f6rderbedarf festgestellt worden?\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"radios\">\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k3foerderbedarfnein\">Nein<\/label><input type=\"radio\" id=\"k3foerderbedarfnein\" name=\"k3foerderbedarf\" value=\"nein\"><\/span>\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k3foerderbedarfja\">Ja<\/label><input type=\"radio\" id=\"k3foerderbedarfja\" name=\"k3foerderbedarf\" value=\"ja\"><\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<hr class=\"trenner\">\r\n\t\t\t\t\t\t3. Gibt es gesundheitliche Herausforderungen, die Einfluss auf den Schulalltag haben oder Dauer-medikation erfordern (z.B. Seh-\/H\u00f6rsch\u00e4digung\/chronische Krankheiten \/Allergien o. \u00e4.?)\t\t\t\t\t\t\r\n\t\t\t\t\t\t<div class=\"radios\">\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k3gesundheitnein\">\r\n\t\t\t\t\t\tNein<\/label><input type=\"radio\" id=\"k3gesundheitnein\" name=\"k3gesundheit\" value=\"nein\"><\/span>\r\n\t\t\t\t\t\t\t<span><label class=\"radiolabel\" for=\"k3gesundheitja\">\r\n\t\t\t\t\t\tJa<\/label><input type=\"radio\" id=\"k3gesundheitja\" name=\"k3gesundheit\" value=\"ja\"><\/span>\r\n\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\t\t<textarea id=\"k3gesundheitdetails\" name=\"k3gesundheitdetails\" rows=\"4\" cols=\"50\">Falls ja, bitte hier angeben:<\/textarea>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\r\n\t\t<hr class=\"trenner\">\r\n        <!--        \r\n\t\tGew&uuml;nschte Schule:                \r\n\t\t<select name=\"kibs\" id=\"kibs\">\r\n            <option>Grundschule (Primary) Hannover<\/option>\r\n            <option>Grundschule (Primary) Fliegerhorst Goslar<\/option>\r\n            <option>Gymnasium (Secondary) Hannover<\/option>\r\n        <\/select>\r\n              \r\n        <hr class=\"trenner\">\r\n        -->\r\n\t\t\r\n\t\t<h3>Information zu Beitr\u00e4gen<\/h3>\r\n\t\t\r\n\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t<h3 id=\"at-28567\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-28567\" aria-expanded=\"false\">A) Kindertagesst\u00e4tte<\/h3>\r\n\t\t\t<div id=\"ac-28567\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\t<h4>Beitr\u00e4ge f\u00fcr st\u00e4dtische gef\u00f6rderte Pl\u00e4tze<\/h4>\r\n\r\nUnser Kontingent von insgesamt 159 Pl\u00e4tzen enth\u00e4lt:\r\n<ul>\r\n<li>50 st\u00e4dtische gef\u00f6rderte Pl\u00e4tze im Kindergarten<\/li>\r\n<li>30 st\u00e4dtische gef\u00f6rderte Pl\u00e4tze in der Krippe<\/li>\r\n<\/ul>\r\nAnspruchsberechtigt sind ausschlie\u00dflich Familien mit Erstwohnsitz im Stadtgebiet Hannover.<br \/>\r\nF\u00fcr diese Pl\u00e4tze ist unbedingt der Nachweis des Einkommens erforderlich.<br \/>\r\nEin st\u00e4dtisch gef\u00f6rderter Kindergartenplatz f\u00fcr Kinder ab dem vollendenten 3. Lebensjahr ist beitragsfrei.<br \/><br \/>\r\nZur Beachtung:<br \/>\r\nDie Nachfrage nach st\u00e4dtisch gef\u00f6rderten Platzen ist stets sehr hoch. Sie k\u00f6nnen nur dann vergeben werden, wenn aus diesem von der Stadt zugesagten Kontingent noch Pl\u00e4tze verf\u00fcgbar sind.<br \/>\r\nDie Beitr\u00e4ge werden auf der Basis der F\u00f6rderstufentabelle der Stadt Hannover erhoben \u2013 diese ist auf der <a href=\"https:\/\/www.hannover.de\/Leben-in-der-Region-Hannover\/Verwaltungen-Kommunen\/Die-Verwaltung-der-Landeshauptstadt-Hannover\/Dezernate-und-Fachbereiche-der-LHH\/Bildung,-Jugend-und-Familie\/Fachbereich-Jugend-und-Familie\/Wirtschaftliche-Jugendhilfe-der-Landeshauptstadt\/Betreuungsentgelte-f%C3%BCr-Tageseinrichtungen\" target=\"_blank\">Website der Stadt Hannover<\/a> verf\u00fcgbar und kann als pdf-Dokument heruntergeladen werden.<br \/>\r\n\r\n<h4>Beitr\u00e4ge f\u00fcr private Pl\u00e4tze<\/h4>\r\n<ul>\r\n<li>Kindergartenplatz monatlich 625,00 \u20ac zzgl. Beitrag F\u00f6rderverein monatlich 15,00 \u20ac<\/li>\r\n<li>Krippenplatz monatlich 765,00 \u20ac zzgl. Beitrag F\u00f6rderverein monatlich 5,00 \u20ac<\/li>\r\n<\/ul>\r\nDie Beitr\u00e4ge zum F\u00f6rderverein werden zur Finanzierung des Musik- und Bewegungsf\u00f6rderungsangebotes eingesetzt.<br \/>\r\nBitte kreuzen Sie die von Ihnen gew\u00fcnschte Option an:<br \/>\r\nIch bin\/wir sind<br \/>\r\n<input type=\"radio\" id=\"html\" name=\"kitaplatz\" value=\"privat\"> an einem privaten Platz interessiert.<br \/>\r\n<input type=\"radio\" id=\"html\" name=\"kitaplatz\" value=\"nurgefoerdert\"> ausschlie\u00dflich an einem st\u00e4dtisch gef\u00f6rderten Platz interessiert (Bitte das Bruttojahreshaushaltseinkommen angeben):<br \/>\r\n<input type=\"radio\" id=\"html\" name=\"kitaplatz\" value=\"gefoerdertbevorzugt\"> an einem st\u00e4dtisch gef\u00f6rderten Platz interessiert, w\u00fcrde(n) aber auch einen privaten Platz nehmen, wenn kein gef\u00f6rderter Platz verf\u00fcgbar ist (Bitte auch hier das Bruttojahreshaushaltseinkommen angeben).<br \/>\r\n<br \/>\r\n<label>Unser Bruttojahreshaushaltseinkommen betr\u00e4gt:<\/label><input type=\"text\" name=\"bjhek\" id=\"bjhek\">\r\nIhren Einkommensnachweis fordert KIBS vor Vertragsschluss an.<br \/>\r\n\r\n<h4>Geschwisterrabatte Kindertagesst\u00e4tte<\/h4>\r\n<ul>\r\n<li>ein zweites Kind erh\u00e4lt 30 % Rabatt<\/li>\r\n<li>ein drittes Kind erh\u00e4lt 50 % Rabatt<\/li>\r\n<\/ul>\r\nDie Zuordnung des Geschwisterrabatts wird gem\u00e4\u00df folgenden Grunds\u00e4tzen vorgenommen:<br \/>\r\nDer Betreuungsintensivste Platz wird jeweils voll berechnet, das\/die n\u00e4chst\u00e4ltere(n) Kind(er) bekommen den Rabatt.<br \/>\r\n<br \/>\r\n(Auf Tabelle klicken zum Download)<br \/>\r\n(Stand: August 2025)<br \/>\r\n<br \/>\r\n<a href=\"https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-kita-krippe-august-2025.pdf\" target=\"_blank\"><img loading=\"lazy\" loading=\"lazy\" decoding=\"async\" width=\"1697\" height=\"1900\" src=\"https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-kita-krippe-august-2025.jpg\" alt=\"\" class=\"wp-image-6225\" srcset=\"https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-kita-krippe-august-2025.jpg 1697w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-kita-krippe-august-2025-268x300.jpg 268w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-kita-krippe-august-2025-915x1024.jpg 915w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-kita-krippe-august-2025-768x860.jpg 768w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-kita-krippe-august-2025-1372x1536.jpg 1372w\" sizes=\"auto, (max-width: 1697px) 100vw, 1697px\"><\/a><br \/><br \/><br \/>\r\n<strong>*1)<\/strong> Optionen Aufnahmegeb\u00fchr: Auswahl Liquidit\u00e4tseinlage oder Spende\r\n<ul>\r\n<li>Liquidit\u00e4tseinlage: Die Aufnahmegeb\u00fchr wird beim Verlassen der Einrichtung erstattet oder mit der Aufnahmegeb\u00fchr unserer Grundschule verrechnet.<\/li>\r\n<li>Spende: Die Aufnahmegeb\u00fchr wird beim Verlassen der Einrichtung nicht erstattet, daf\u00fcr wird f\u00fcr die Grundschule aber auch keine Aufnahmegeb\u00fchr f\u00e4llig.<\/li>\r\n<\/ul>\r\n<strong>*2)<\/strong> Der monatliche Beitrag wird auf Basis des Einkommens der Erziehungsberechtigten in 10 Stufen eingeteilt und liegt zwischen 0,00 \u20ac - 480,00 \u20ac. F\u00fcr genauere Informationen <a href=\"https:\/\/www.hannover.de\/Leben-in-der-Region-Hannover\/Verwaltungen-Kommunen\/Die-Verwaltung-der-Landeshauptstadt-Hannover\/Dezernate-und-Fachbereiche-der-LHH\/Bildung,-Jugend-und-Familie\/Fachbereich-Jugend-und-Familie\/Wirtschaftliche-Jugendhilfe-der-Landeshauptstadt\/Betreuungsentgelte-f%C3%BCr-Tageseinrichtungen\/Ausf%C3%BChrliche-Informationen-und-Regelungen-zu-den-Betreuungsentgelten-in-Kindertagesst%C3%A4tten-Krippe,-Kindergarten-und-Hort-im-Stadtgebiet\" target=\"_blank\">klicken Sie bitte hier<\/a>.<br \/><br \/>\r\n<strong>*3)<\/strong> Kinder ab drei Jahren sind beitragsfrei.<br \/>\r\n<br \/>\r\n<strong>Bitte beachten Sie, dass die st\u00e4dtisch gef\u00f6rderten Pl\u00e4tze leider nur begrenzt verf\u00fcgbar sind und vorrangig an Familien mit Wohnsitz in Hannover Stadt vergeben werden. Zudem haben wir eine hohe Nachfrage bez\u00fcglich dieser Pl\u00e4tze.<\/strong>\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\t\t\r\n\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t<h3 id=\"at-28568\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-28568\" aria-expanded=\"false\">B) Schule<\/h3>\r\n\t\t\t<div id=\"ac-28568\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\tIn der Schule gibt es nur private Pl\u00e4tze mit einkommensabh\u00e4ngigen Elternbeitr\u00e4gen.<br \/>\r\nF\u00fcr die Berechnung ihres Elternbeitrags ben\u00f6tigen wir die Angabe des positiven Jahresbruttohaushaltseinkommens der Familie. Bei freiwilliger Zahlung des H\u00f6chstbeitrags entf\u00e4llt die Angabe.\r\n<br \/><br \/>\r\nDie Schulgeb\u00fchren betragen\r\n<ul>\r\n<li>In der Grundschule mindestens 245,00 \u20ac und h\u00f6chstens 1.042,00 \u20ac monatlich<\/li>\r\n<li>Im Gymnasium (ab Kl. 5) mindestens 371,00 \u20ac und h\u00f6chstens 1.203,00 \u20ac monatlich<\/li>\r\n<li>In der Grundschule mindestens 245,00 \u20ac und h\u00f6chstens 1.042,00 \u20ac monatlich<\/li>\r\n<\/ul>\r\n\r\nGeschwisterrabatte\r\n<ul>\r\n<li>Das \u00e4lteste Kind zahlt den vollen Beitrag<\/li>\r\n<li>Das n\u00e4chstj\u00fcngere Kind erh\u00e4lt 30 % Rabatt auf das monatliche Schulgeld<\/li>\r\n<li>Das dritte Kind erh\u00e4lt 50 % Rabatt auf das monatliche Schulgeld<\/li>\r\n<li>Weitere Kinder erhalten Rabatt gem\u00e4\u00df vertraglicher Einzelabsprache<\/li>\r\n<\/ul>\r\nMit der automatisierten Eingangsbest\u00e4tigung dieses Bogens erhalten Sie einen Link zum Beitragsrechner, um das Schulgeld Ihres Kindes selbst zu ermitteln.\r\nDas Einkommen ist nach Zusage der Aufnahme in die erste Klasse bzw. erfolgreichen Probetagen durch Vorlage des Einkommenssteuerbescheids oder einer vorl\u00e4ufigen Einkommenssch\u00e4tzung mit entsprechenden Belegen nachzuweisen. <strong>Der endg\u00fcltige Einkommensteuerbescheid muss sp\u00e4testens zum Schulbeginn vorgelegt werden.<\/strong>\r\n\r\n<h4>Kosten\u00fcbersichten Schule<\/h4>\r\n(Auf Tabelle klicken zum Download)<br \/>\r\n(Stand: August 2025)<br \/>\r\n<br \/>\r\n<a href=\"https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-schule-august-2025.pdf\" target=\"_blank\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"1538\" height=\"2403\" src=\"https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-schule-august-2025.jpg\" alt=\"\" class=\"wp-image-6227\" srcset=\"https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-schule-august-2025.jpg 1538w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-schule-august-2025-192x300.jpg 192w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-schule-august-2025-655x1024.jpg 655w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-schule-august-2025-768x1200.jpg 768w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-schule-august-2025-983x1536.jpg 983w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/06\/kostenuebersicht-schule-august-2025-1311x2048.jpg 1311w\" sizes=\"(max-width: 1538px) 100vw, 1538px\"><\/a>\r\n<br \/>\r\nF\u00fcr beide Schulformen gilt dar\u00fcber hinaus:\r\n<ul>\r\n<li>Standard-Jahresbeitrag KIBS-F\u00f6rderverein 10,00 \u20ac<\/li>\r\n<li>Kosten f\u00fcr Schulkleidung gem\u00e4\u00df Angebot der KIBS-Kooperationspartner \u2013 siehe Links Website<\/li>\r\n<\/ul>\r\n<br \/>\r\n<a href=\"https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/uebersicht-schulgeld.png\" class=\"fancybox image\" aria-controls=\"fancybox-wrap\" aria-haspopup=\"dialog\"><img fetchpriority=\"high\" fetchpriority=\"high\" decoding=\"async\" width=\"789\" height=\"1024\" src=\"https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/uebersicht-schulgeld-789x1024.png\" alt=\"\" class=\"wp-image-6219\" srcset=\"https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/uebersicht-schulgeld-789x1024.png 789w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/uebersicht-schulgeld-231x300.png 231w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/uebersicht-schulgeld-768x996.png 768w, https:\/\/www.kaemmerinternational.de\/hannover\/wp-content\/uploads\/2025\/05\/uebersicht-schulgeld.png 1100w\" sizes=\"(max-width: 789px) 100vw, 789px\"><\/a>\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\r\n\t\t<hr class=\"trenner\">\r\n\t\t\t\t\r\n\t\t<div class=\"wp-block-pb-accordion-item c-accordion__item js-accordion-item is-read is-open\" data-initially-open=\"false\" data-click-to-close=\"true\" data-auto-close=\"true\" data-scroll=\"false\" data-scroll-offset=\"0\">\r\n\t\t<h3 id=\"at-28569\" class=\"c-accordion__title js-accordion-controller\" role=\"button\" tabindex=\"0\" aria-controls=\"ac-28569\" aria-expanded=\"false\">Bankverbindung<\/h3>\r\n\t\t\t<div id=\"ac-28569\" class=\"c-accordion__content\" style=\"display: none;\">\r\n\t\t\t\t\ufeff<p>Wenn Ihr Kind zu KIBS wechseln soll und zu Probetagen eingeladen wird, erheben wir f\u00fcr die Deckung der anfallenden Kosten 50,00 Euro.Die Zahlungen erfolgen ausschlie\u00dflich per Banklastschrift. Bitte geben Sie nachfolgend Ihre Kontoverbindung an:<\/p>\r\n\r\n<label for=\"kontoinhaber\">Kontoinhaber:in<\/label>\r\n<input type=\"text\" name=\"kontoinhaber\" id=\"kontoinhaber\" required><br \/>\r\n\r\n<label for=\"iban\">IBAN<\/label>\r\n<input type=\"text\" name=\"iban\" id=\"iban\" required><br \/>\r\n\r\n<label for=\"bic\">BIC<\/label>\r\n<input type=\"text\" name=\"bic\" id=\"bic\" required><br \/>\r\n\r\n<label for=\"bankname\">Name der Bank<\/label>\r\n<input type=\"text\" name=\"bankname\" id=\"bankname\" required><br \/>\r\n\r\n<p><strong>Stornobedingungen:<\/strong><\/p>\r\n<ul>\r\n    <li>Absage 1 Woche vor dem Termin: 10,00 \u20ac<\/li>\r\n    <li>Absage 3 Tage vor dem Termin: 25,00 \u20ac<\/li>\r\n    <li>Absage 1 Tag vor dem Termin: 50,00 \u20ac<\/li>\r\n<\/ul>\r\n<p>Bei nachweisbar krankheitsbedingter Absage sowie Verschiebung wird keine Stornogeb\u00fchr erhoben.<\/p>\r\n\r\n<p>Wir verarbeiten Ihre personenbezogenen Daten (Name, Kontoverbindung) ausschlie\u00dflich zum Zweck der Abwicklung Ihrer Anmeldung bei KIBS und der Zahlungsabwicklung.<br\/>Weitere Informationen finden Sie in unserer <a href=\"https:\/\/www.kaemmerinternational.de\/hannover\/datenschutzerklaerung\/\" target=\"_blank\">Datenschutzerkl\u00e4rung<\/a>.<\/p>\r\n\r\n<!-- Opt-in Checkbox -->\r\n<label for=\"agreement\">\r\n    <input type=\"checkbox\" name=\"agreement\" id=\"agreement\" required>\r\n    Ich stimme der Verarbeitung meiner personenbezogenen Daten gem\u00e4\u00df der Datenschutzerkl\u00e4rung zu.<br\/>Mir ist bekannt, dass ich diese Einwilligung jederzeit mit Wirkung f\u00fcr die Zukunft widerrufen kann.\r\n<\/label><br \/>\r\n\r\n<!-- Opt-in Checkbox f\u00fcr AGB\/Stornobedingungen -->\r\n<label for=\"terms\">\r\n    <input type=\"checkbox\" name=\"terms\" id=\"terms\" required>\r\n    Ich habe die oben genannten Stornobedingungen gelesen und stimme diesen zu.\r\n<\/label><br \/>\r\n\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t\t\r\n        <!--\r\n\t\t<hr class=\"trenner\">\r\n\t\t\r\n\t\t\r\n\t\t<div class=\"g-recaptcha\" id=\"rcaptcha\"  data-sitekey=\"6LfZaS8qAAAAAG2xNG-4vrDPLpk1DIQ4kHdrI7OF\"><\/div> \r\n\t\t<input type=\"hidden\" name=\"g-recaptcha-response\" value=\"6LfZaS8qAAAAAG2xNG-4vrDPLpk1DIQ4kHdrI7OF\">\r\n\t\t-->\r\n\t\t<span id=\"captcha\" style=\"color:red\" \/><\/span> <!-- this will show captcha errors -->\r\n\r\n        <button type=\"submit\" id=\"submitSchule\" class=\"g-recaptcha\" \r\n        data-sitekey=\"6LfZaS8qAAAAAG2xNG-4vrDPLpk1DIQ4kHdrI7OF\" \r\n        data-callback='onSubmit' \r\n        data-action='submit'>Senden<\/button>\r\n        <div id=\"submitting\">Ihre Angaben werden gesendet. Bitte lesen Sie die Informationen auf der folgenden Seite sorgf\u00e4ltig!.<\/div>\r\n        <input type=\"hidden\" name=\"formlang\" value=\"de\">\r\n        <input type=\"hidden\" name=\"eingabe\" value=\"true\">\r\n    <\/form>\r\n\t\r\n\t<!--\r\n\t<hr class=\"trenner\">\r\n\t -->\r\n\t\r\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-5479","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.kaemmerinternational.de\/hannover\/wp-json\/wp\/v2\/pages\/5479","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kaemmerinternational.de\/hannover\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.kaemmerinternational.de\/hannover\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.kaemmerinternational.de\/hannover\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kaemmerinternational.de\/hannover\/wp-json\/wp\/v2\/comments?post=5479"}],"version-history":[{"count":0,"href":"https:\/\/www.kaemmerinternational.de\/hannover\/wp-json\/wp\/v2\/pages\/5479\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.kaemmerinternational.de\/hannover\/wp-json\/wp\/v2\/media?parent=5479"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}